{"id":11801,"date":"2020-02-11T16:10:14","date_gmt":"2020-02-11T15:10:14","guid":{"rendered":"https:\/\/thehiketribe.com\/de\/?p=11801"},"modified":"2022-07-04T19:45:16","modified_gmt":"2022-07-04T17:45:16","slug":"fischerweg","status":"publish","type":"post","link":"https:\/\/thehiketribe.com\/de\/fischerweg\/","title":{"rendered":"Fischerweg: K\u00fcstenwandern auf der Rota Vicentina"},"content":{"rendered":"<p><b>Der Fischerweg ist ein K\u00fcstenwanderweg im Naturpark s\u00fcdwestliches Alentejo und Vicentinische K\u00fcste in Portugal. Der mehrt\u00e4gige Wanderweg gilt als einer der sch\u00f6nsten K\u00fcstenwanderwege der Welt.<\/b><\/p>\n<p>Der Fischerpfad l\u00e4sst sich in vier Tagesetappen erwandern und ist mit gr\u00fcn-blauen Wanderwegweisern super ausgeschildert. Hier findest du die wichtigsten Informationen \u00fcber die einzelnen Tagesetappen, Unterk\u00fcnfte auf dem Weg, Anreise und Packliste.<\/p>\n<hr>\n<h2>Eckdaten Fischerweg<\/h2>\n<ul>\n<li>L\u00e4nge: 75 Kilometer (120 mitsamt zus\u00e4tzlicher Rundwanderwege) <\/li>\n<li>Startpunkt: Porto Covo<\/li>\n<li>Ziel: Odeceixe<\/li>\n<li>Teil der Rota Vicentina<\/li>\n<li>Etappen: Vier (+f\u00fcnf erg\u00e4nzende Strecken)<\/li>\n<li>Art: K\u00fcstenwanderweg\/Fernwanderweg<\/li>\n<li>Schwierigkeitsgrad: Mittelschwer (teilweise sind Kondition und Schwindelfreiheit gefragt)<\/li>\n<\/ul>\n<hr>\n<h2>Beste Reisezeit f\u00fcr den Fischerweg<\/h2>\n<p>Die ideale Reisezeit, um auf dem Fischerpfad zu wandern sind die Monate von <b>September bis Juni<\/b>, wobei darauf zu achten ist, dass es in den Wintermonaten von November bis Februar auch oft regnet. <\/p>\n<p>Die Sommermonate Juli und August sind sehr heiss und da du auf dem Fischerweg konstant der Sonne ausgesetzt bist viel zu anstrengend zum Wandern. <\/p>\n<p><em><\/p>\n<ul>\n<b>Lesetipp:<\/b> An diesen tollen Orten kannst du noch in <a href=\"https:\/\/thehiketribe.com\/de\/portugal\/\" rel=\"noopener\" target=\"_blank\">Portugal Wandern<\/a>.<\/ul>\n<p><\/em><\/p>\n<hr>\n<h2>Etappen des Fischerweg<\/h2>\n<h3>Etappe 1: Porto Covo bis Vila Nova de Milfontes<\/h3>\n<p>Der Weg von Porto Covo bis Vila Nova de Milfontes verl\u00e4uft eher einsam durch wilde Natur &#8211; D\u00fcnen und Strand &#8211; und mit konstantem Blick auf den Atlantik.<\/p>\n<p>Die erste Etappe ist die &#8222;K\u00f6nigsetappe&#8220; und ist konditionell besonders anspruchsvoll. Denn du versinkst bei jedem Schritt im Sand, daher geht die Wanderung eher langsam voran und Etappe 1 zieht sich mit 6 Stunden ordentlich in die L\u00e4nge.<\/p>\n<ul>\n<li>L\u00e4nge: 20 km<\/li>\n<li>Dauer: 6 Stunden<\/li>\n<li>Schwierigkeitsgrad: Mittel<\/li>\n<\/ul>\n<hr>\n<h3>Etappe 2: Vila Nova de Milfontes bis Almograve<\/h3>\n<p>Die zweite Etappe des Trilho dos Pescadores ist um einiges entspannter als die erste Etappe. Sie f\u00fchrt \u00fcber den Rio Mira entlang der h\u00fcgeligen K\u00fcste, die mit Wildblumen bewachsen ist.  <\/p>\n<ul>\n<li>L\u00e4nge: 15 km<\/li>\n<li>Dauer: 4 Stunden<\/li>\n<li>Schwierigkeitsgrad: Leicht<\/li>\n<\/ul>\n<hr>\n<h3>Etappe 3: Almograve nach Zambujera do Mar<\/h3>\n<p>Auf der Etappe von Almograve nach Zambujera do Mar wanderst du entlang rotgef\u00e4rbter Klippen, die Heimat und Brutst\u00e4tten von 20 Vogelarten sind und kommst an kleinen traditionellen Fischerh\u00e4fen vorbei. Am Leuchtturm vom Kap Sardao kannst du eine sch\u00f6ne Pause einlegen und den Fischern bei ihrer Arbeit zuschauen.<\/p>\n<ul>\n<li>L\u00e4nge: 22 km<\/li>\n<li>Dauer: 7 Stunden <\/li>\n<li>Schwierigkeitsgrad: Mittel<\/li>\n<\/ul>\n<hr>\n<h3>Etappe 4: Zambujera do Mar bis Odeceixe<\/h3>\n<p>Die Etappe von Zambujera do Mar bis Odeceixe bietet spektakul\u00e4re Aussichten. Die Wanderung verl\u00e4uft entlang verschiedener Str\u00e4nde bis zum Fischerhafen von Azenha do Mar und weiter zum majest\u00e4tischen Aussichtspunkt Ponta em Branco. Von hier aus siehst du den sch\u00f6nen Strand von Odeceixe und die Berge im Hinterland und l\u00e4ufst dann weiter am Fluss entlang nach Odeceixe.<\/p>\n<ul>\n<li>L\u00e4nge: 18 km<\/li>\n<li>Dauer: 6 Stunden<\/li>\n<li>Schwierigkeitsgrad: Mittel<\/li>\n<\/ul>\n<hr>\n<blockquote><p><b>Gut zu wissen:<\/b> Der Fischerpfad ist kein einfacher Wanderweg. Er ist an manchen Stellen ausgesetzt, steil und f\u00fchrt an Abgr\u00fcnden entlang. Es gibt felsige, aber auch sandige Passagen, die einiges an Kondition und Trittsicherheit fordern. Au\u00dferdem gibt es nicht viele M\u00f6glichkeiten eine Pause einzulegen. Daher ist der Fischerpfad f\u00fcr bereits erfahrene Wanderer und nicht besonders f\u00fcr Familien mit Kindern geeignet.<\/p><\/blockquote>\n<hr>\n<p>Das Sch\u00f6nste auf dem K\u00fcstenwanderweg ist, dass du eine konstante tolle Aussicht auf den Atlantik hast und imposante Felsw\u00e4nde, sch\u00f6ne Str\u00e4nde und wilde Natur deinen Weg pr\u00e4gen und du die M\u00f6glichkeit hast an Orte zu kommen, die nur zu Fu\u00df erreichbar sind. <\/p>\n<p>Der Fernwanderweg f\u00fchrt komplett durch den gesch\u00fctzten Naturpark \u201eSudoeste-Alentejano e Costa Vicentina\u201c. Man wandert also durch unber\u00fchrte Natur, ohne Hotels, Autos oder sonstiges, was dem Naturerlebnis in die Quere kommt. <\/p>\n<p>Au\u00dferdem sind die Etappenziele Porto Covo, Vila Nova de Milfontes und Odeceixe sehr h\u00fcbsche und charmante D\u00f6rfer, die du sonst vielleicht nicht besichtigen w\u00fcrdest.<\/p>\n<p>Wer weiter auf dem Historischen Weg wandern will kann direkt ab Odeceixe starten, denn das Dorf ist nicht nur Ziel des Fischerpfads, sondern auch Start des Historischen Wegs.<\/p>\n<hr>\n<h2>Anreise<\/h2>\n<p>Wenn du von Deutschland anreist kannst du entweder nach Lissabon oder Faro fliegen. <\/p>\n<p>Von Lissabon aus kannst du direkt mit dem Rede Expressos Bus zum Startpunkt Porto Covo fahren. Die Fahrt dauert etwa drei Stunden und die Tickets k\u00f6nnen Online bei Rede Expressos gekauft werden.<\/p>\n<p>Von Faro kannst du mit Zug oder Bus bis Lagos fahren und von dort mit dem Bus bis Porto Covo fahren. Die Fahrt ist jedoch wesentlich teurer und l\u00e4nger. Die Tickets sind ebenso bei Rede Expressos zu kaufen. <\/p>\n<p>Hier kommst du zur <a href=\"https:\/\/www.rede-expressos.pt\/en\" rel=\"noopener noreferrer\" target=\"_blank\">Webseite von Rede Expressos<\/a>.<\/p>\n<hr>\n<h2>Unterk\u00fcnfte und Zelten auf dem Fischerweg<\/h2>\n<p>Generell ist Wildcampen in Portugal verboten, so auch im Naturpark. Wer auf den Fernwanderweg Etappenzielen Porto Covo, Vila Nova de Milfontes, Zambujera do Mar und Odeceixe zelten will findet aber einige Campingpl\u00e4tze dazu.<\/p>\n<ul>\n<strong>Porto Covo<\/strong>: Parque de Campismo Porto Covo<br \/>\n<strong>Vila Nova de Milfontes<\/strong>: Camping Milfontes<br \/>\n<strong>Zambujera do Mar<\/strong>: Camping Villa Park Zambujeira<br \/>\n<strong>Odeceixe<\/strong>: Camping S\u00e3o Miguel (etwas au\u00dferhalb von Odeceixe)\n<\/ul>\n<p>Wer ein festes Dach \u00fcber dem Kopf haben m\u00f6chte kann aber auch einige Bed &#038; Breakfasts, Hotels und G\u00e4steh\u00e4user finden. Auf der offiziellen Webseite der Rota Vicentina findest du eine <a href=\"https:\/\/rotavicentina.com\/en\/map\/\" rel=\"noopener noreferrer\" target=\"_blank\">Karte der Rota Vicentina mit Unterk\u00fcnften und vielem mehr<\/a>.<\/p>\n<h3>Wandern ohne Gep\u00e4ck<\/h3>\n<p>Wer fr\u00fch genug die Unterk\u00fcnfte bucht und benachrichtigt kann arrangieren, dass die Vermieter den Gep\u00e4cktransport untereinander organisieren. Das kann eine gro\u00dfe Erleichterung sein, denn beim Wandern wird es zum Einen ganz sch\u00f6n warm und zum Anderen sp\u00fcrst du irgendwann jedes Kilogramm auf dem R\u00fccken. <\/p>\n<hr>\n<h2>Packliste<\/h2>\n<p>Auf dem Fischerweg brauchst du das ganze Jahr \u00fcber <b>Sonnenschutz<\/b>. In den Wintermonaten kann es aber auch mal regnen, daf\u00fcr eignen sich <b>Regenjacke und Regenhose<\/b>. Um den Sand so gut f\u00fcr m\u00f6glich aus den Schuhen zu halten eignen sich <b>Gamaschen<\/b>, die sonst vor Schnee sch\u00fctzen. <\/p>\n<p>Zwar gibt es auf den Etappenziele kleine Superm\u00e4rkte, f\u00fcr die langen Tagesetappen solltest du jedoch mindestens zwei Liter Wasser dabeihaben. Wer sich entscheidet zu Campen muss au\u00dferdem noch Zelt, Isomatte und Schlafsack transportieren. Das ist unsere <b>Packliste f\u00fcr den Fisherman&#8217;s Trail<\/b>.<\/p>\n<ul>\n<li>Trekkingrucksack<\/li>\n<li>Wanderschuhe und Blasenpflaster<\/li>\n<li>Gamaschen (gegen Sand)<\/li>\n<li>Wanderhose<\/li>\n<li>Wandershirt<\/li>\n<li>Wandersocken<\/li>\n<li>Funktionstuch\/Buff<\/li>\n<li>Windbreaker<\/li>\n<li>Regenjacke und Regenhose bei schlechtem Wetter<\/li>\n<li>Ausreichend Trinken (mindestens 2 L pro Person)<\/li>\n<li>Sonnenschutz: Kopfbedeckung, Sonnencreme, Sonnenbrille<\/li>\n<li>Wasserfilter<\/li>\n<li>Kleidung f\u00fcr den Abend und die \u00dcbernachtung<\/li>\n<li>Beim Zelten: Zelt, Isomatte, Schlafsack, Flipflops<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Der Fischerweg ist ein K\u00fcstenwanderweg im Naturpark s\u00fcdwestliches Alentejo und Vicentinische K\u00fcste in Portugal. Der mehrt\u00e4gige Wanderweg gilt als einer der sch\u00f6nsten K\u00fcstenwanderwege der Welt. Der Fischerpfad l\u00e4sst sich in vier Tagesetappen erwandern und ist mit gr\u00fcn-blauen Wanderwegweisern super ausgeschildert. Hier findest du die wichtigsten Informationen \u00fcber die einzelnen Tagesetappen,<\/p>\n","protected":false},"author":4,"featured_media":11844,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-11801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reiseziele"],"_links":{"self":[{"href":"https:\/\/thehiketribe.com\/de\/wp-json\/wp\/v2\/posts\/11801"}],"collection":[{"href":"https:\/\/thehiketribe.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thehiketribe.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thehiketribe.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/thehiketribe.com\/de\/wp-json\/wp\/v2\/comments?post=11801"}],"version-history":[{"count":10,"href":"https:\/\/thehiketribe.com\/de\/wp-json\/wp\/v2\/posts\/11801\/revisions"}],"predecessor-version":[{"id":12905,"href":"https:\/\/thehiketribe.com\/de\/wp-json\/wp\/v2\/posts\/11801\/revisions\/12905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thehiketribe.com\/de\/wp-json\/wp\/v2\/media\/11844"}],"wp:attachment":[{"href":"https:\/\/thehiketribe.com\/de\/wp-json\/wp\/v2\/media?parent=11801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thehiketribe.com\/de\/wp-json\/wp\/v2\/categories?post=11801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thehiketribe.com\/de\/wp-json\/wp\/v2\/tags?post=11801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}